{"id":160,"date":"2022-06-12T08:48:34","date_gmt":"2022-06-12T06:48:34","guid":{"rendered":"https:\/\/www.fermeduvieuxchene.fr\/?page_id=160"},"modified":"2026-02-05T17:22:43","modified_gmt":"2026-02-05T16:22:43","slug":"la-chevre-poitevine","status":"publish","type":"page","link":"https:\/\/www.fermeduvieuxchene.fr\/index.php\/la-chevre-poitevine\/","title":{"rendered":"LA CH\u00c8VRE POITEVINE"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"160\" class=\"elementor elementor-160\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0e1620 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0e1620\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-73deef5\" data-id=\"73deef5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b62bb1 elementor-widget elementor-widget-text-editor\" data-id=\"2b62bb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le berceau de la race Poitevine se situe aux alentours des sources de la S\u00e8vre, dans le Centre-Ouest de la France en r\u00e9gion Poitou-Charentes.<\/p><p><strong>Type<\/strong>: La ch\u00e8vre poitevine est un animal de format moyen et d\u2019aspect longiligne.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-788f962\" data-id=\"788f962\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64c5159 elementor-widget elementor-widget-image\" data-id=\"64c5159\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/AB08402-Modifier-1024x683-1.jpg?fit=1024%2C683&amp;ssl=1\" class=\"attachment-large size-large wp-image-166\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/AB08402-Modifier-1024x683-1.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/AB08402-Modifier-1024x683-1.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/AB08402-Modifier-1024x683-1.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3e4e2bf\" data-id=\"3e4e2bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b45e82 elementor-widget elementor-widget-image\" data-id=\"6b45e82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/PosterPoitevine.jpg?ssl=1\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"PosterPoitevine\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYyLCJ1cmwiOiJodHRwczpcL1wvd3d3LmZlcm1lZHV2aWV1eGNoZW5lLmZyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wNlwvUG9zdGVyUG9pdGV2aW5lLmpwZyJ9\">\n\t\t\t\t\t\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/elementor\/thumbs\/PosterPoitevine-pq70emv63h7t9td13ld5bly3tmrrqf5lcdz39dv2m8.jpg?w=1200&#038;ssl=1\" title=\"PosterPoitevine\" alt=\"PosterPoitevine\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a59f40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a59f40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1aa0fcc\" data-id=\"1aa0fcc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a64d8c elementor-widget elementor-widget-text-editor\" data-id=\"7a64d8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Robe et poil<\/strong>: La robe comporte des poils d\u2019un brun plus ou moins fonc\u00e9, allant parfois jusqu\u2019au noir: la couleur recherch\u00e9 est le brun fonc\u00e9. Le blanc occupe le ventre, la face int\u00e9rieure des membres, le dessous de la queue. Raie blanche de chaque cot\u00e9 du chanfrein. La robe du bouc est g\u00e9n\u00e9ralement plus fonc\u00e9e. Les raies blanches de la face s\u2019estompent avec l\u2019age et disparaissent parfois. Chez la femelles, les poils sont plus d\u00e9velopp\u00e9s sur les \u00e9paules et sur le cou.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b578531 elementor-widget elementor-widget-text-editor\" data-id=\"2b578531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>T\u00eates <\/strong>:\u00a0triangulaire, garrot en coin, poitrine profonde, ligne de dessus droite; le cou est long, souple, le port de cou est fier, la\u00a0pr\u00e9sence\u00a0de pendeloques (ou pampilles) est souhait\u00e9e.<\/p><p><strong>Membres <\/strong>: fin<\/p><p><strong>Mamelle <\/strong>: allong\u00e9 et r\u00e9guli\u00e8re. poss\u00e8de deux trayons volumineux. Peau souple et tr\u00e9s mobile.<\/p><p><strong>Format <\/strong>: poids, mensurations: la taille pour les boucs oscille entre 75 cm et 90 cm et pour les femelle entre 75 cm et 80 cm.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f230cb1\" data-id=\"f230cb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9dd42ed elementor-widget elementor-widget-image\" data-id=\"9dd42ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"782\" height=\"782\" src=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/AB08334-Modifier-1024x782-1.jpg?fit=782%2C782&amp;ssl=1\" class=\"attachment-large size-large wp-image-165\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c38c728 elementor-widget elementor-widget-text-editor\" data-id=\"c38c728\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Poids des m\u00e2les<\/strong> : 55 \u00e0 75 kg<\/p><p><strong>Poids des femelles<\/strong> : 40 \u00e0 60 kg<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1a98d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1a98d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6ee8aae\" data-id=\"6ee8aae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e141ba7 elementor-widget elementor-widget-image\" data-id=\"e141ba7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"683\" height=\"683\" src=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/AB08516-Modifier-2-1024x683-1.jpg?fit=683%2C683&amp;ssl=1\" class=\"attachment-large size-large wp-image-169\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Bouc<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-35b09c1\" data-id=\"35b09c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa9d804 elementor-widget elementor-widget-image\" data-id=\"aa9d804\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/AB08614-Modifier-768x1151-1.jpg?fit=683%2C1024&amp;ssl=1\" class=\"attachment-large size-large wp-image-164\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/AB08614-Modifier-768x1151-1.jpg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/AB08614-Modifier-768x1151-1.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/AB08614-Modifier-768x1151-1.jpg?resize=683%2C1024&amp;ssl=1 683w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Chevrette<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fce7571\" data-id=\"fce7571\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a98d72 elementor-widget elementor-widget-image\" data-id=\"3a98d72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"790\" height=\"790\" src=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/AB08686-Modifier-1024x790-1.jpg?fit=790%2C790&amp;ssl=1\" class=\"attachment-large size-large wp-image-163\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Bouquillon<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-937889e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"937889e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8945e44\" data-id=\"8945e44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38bb809 elementor-widget elementor-widget-text-editor\" data-id=\"38bb809\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Historique<\/strong><\/h5><p>D\u00e8s l\u2019origine de la domestication, les ch\u00e8vres ont accompagn\u00e9es les populations; des gaulois aux romains, des sarrasins aux r\u00e9voltes paysannes, la ch\u00e8vre poitevines s\u2019est enracin\u00e9es dans les terres du pourtour du marais poitevin. Compos\u00e9e de plus de 55 000 t\u00eates au d\u00e9but du XX<sup>\u00e8me<\/sup> si\u00e8cle, une violente \u00e9pid\u00e9mie de fi\u00e8vre aphteuse d\u00e9cime les populations en 1920. Les troupeaux sont reconstitu\u00e9s avec des souches pr\u00e9lev\u00e9es dans les Alpes. Ainsi, au fil du temps, les troupeaux d\u2019Alpin et Saanen se d\u00e9veloppent au d\u00e9triment des Poitevins dont les effectifs n\u2019ont cess\u00e9 de diminuer.<\/p><p>Afin de redynamiser la race, l\u2019Union des Coop\u00e9ratives de laiterie met en place un contr\u00f4le laitier pour am\u00e9liorer ses performances d\u00e8s 1947. Dans le m\u00eame temps, un livre g\u00e9n\u00e9alogique est ouvert et son standard est d\u00e9fini. Malgr\u00e9 tout, les effectifs continuent de r\u00e9gresser,\u00a0le travail de s\u00e9lection g\u00e9n\u00e9tique, aid\u00e9 par les lois de modernisation de 1962, favorise les races Alpines et Saanen, l\u2019intensification et la sp\u00e9cialisation des syst\u00e8mes de production laissent de c\u00f4t\u00e9 la Poitevine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca5d104 eael-contact-form-7-button-align-left eael-contact-form-7-button-custom elementor-widget elementor-widget-eael-contact-form-7\" data-id=\"ca5d104\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-contact-form-7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eael-contact-form-7-wrapper\">\n                <div class=\"eael-contact-form eael-contact-form-7 eael-contact-form-ca5d104 placeholder-show eael-contact-form-align-default\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1074-o1\" lang=\"fr-FR\" dir=\"ltr\" data-wpcf7-id=\"1074\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/160#wpcf7-f1074-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1074\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1074-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><b>Un renseignement, un devis, contactez-moi par le formulaire.<\/b><b><br \/>\n<label> Nom<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label><br \/>\n<label> Pr\u00e9nom<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-forname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-forname\" \/><\/span> <\/label><br \/>\n<label> Adresse<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Coordo\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Coordo\" \/><\/span> <\/label><br \/>\n<label> Code postal<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"CP\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"CP\" \/><\/span><\/label><br \/>\n<label> Ville<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"ville\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"ville\" \/><\/span> <\/label><br \/>\n<label> D\u00e9partement<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-453\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"menu-453\"><option value=\"01 \tAin\">01 \tAin<\/option><option value=\"02 \tAisne\">02 \tAisne<\/option><option value=\"03 \tAllier\">03 \tAllier<\/option><option value=\"04 \tAlpes-de-Haute-Provence\">04 \tAlpes-de-Haute-Provence<\/option><option value=\"05 \tHautes-Alpes\">05 \tHautes-Alpes<\/option><option value=\"06 \tAlpes-Maritimes\">06 \tAlpes-Maritimes<\/option><option value=\"07 \tArd\u00e8che\">07 \tArd\u00e8che<\/option><option value=\"08 \tArdennes\">08 \tArdennes<\/option><option value=\"09 \tAri\u00e8ge\">09 \tAri\u00e8ge<\/option><option value=\"10 \tAube\">10 \tAube<\/option><option value=\"11 \tAude\">11 \tAude<\/option><option value=\"12 \tAveyron\">12 \tAveyron<\/option><option value=\"13 \tBouches-du-Rh\u00f4ne\">13 \tBouches-du-Rh\u00f4ne<\/option><option value=\"14 \tCalvados\">14 \tCalvados<\/option><option value=\"15 \tCantal\">15 \tCantal<\/option><option value=\"16 \tCharente\">16 \tCharente<\/option><option value=\"17 \tCharente-Maritime\">17 \tCharente-Maritime<\/option><option value=\"18 \tCher\">18 \tCher<\/option><option value=\"19 \tCorr\u00e8ze\">19 \tCorr\u00e8ze<\/option><option value=\"2A Corse-du-Sud\">2A Corse-du-Sud<\/option><option value=\"2B Haute-Corse\">2B Haute-Corse<\/option><option value=\"21 \tC\u00f4te-d&#039;Or\">21 \tC\u00f4te-d&#039;Or<\/option><option value=\"22 \tC\u00f4tes-d&#039;Armor\">22 \tC\u00f4tes-d&#039;Armor<\/option><option value=\"23 \tCreuse\">23 \tCreuse<\/option><option value=\"24 \tDordogne\">24 \tDordogne<\/option><option value=\"25 \tDoubs\">25 \tDoubs<\/option><option value=\"26 \tDr\u00f4me\">26 \tDr\u00f4me<\/option><option value=\"27 \tEure\">27 \tEure<\/option><option value=\"28 \tEure-et-Loir\">28 \tEure-et-Loir<\/option><option value=\"29 \tFinist\u00e8re\">29 \tFinist\u00e8re<\/option><option value=\"30 \tGard\">30 \tGard<\/option><option value=\"31 \tHaute-Garonne\">31 \tHaute-Garonne<\/option><option value=\"32 \tGers\">32 \tGers<\/option><option value=\"33 \tGironde\">33 \tGironde<\/option><option value=\"34 \tH\u00e9rault\">34 \tH\u00e9rault<\/option><option value=\"35 \tIlle-et-Vilaine\">35 \tIlle-et-Vilaine<\/option><option value=\"36 \tIndre\">36 \tIndre<\/option><option value=\"37 \tIndre-et-Loire\">37 \tIndre-et-Loire<\/option><option value=\"38 \tIs\u00e8re\">38 \tIs\u00e8re<\/option><option value=\"39 \tJura\">39 \tJura<\/option><option value=\"40 \tLandes\">40 \tLandes<\/option><option value=\"41 \tLoir-et-Cher\">41 \tLoir-et-Cher<\/option><option value=\"42 \tLoire\">42 \tLoire<\/option><option value=\"43 \tHaute-Loire\">43 \tHaute-Loire<\/option><option value=\"44 \tLoire-Atlantique\">44 \tLoire-Atlantique<\/option><option value=\"45 \tLoiret\">45 \tLoiret<\/option><option value=\"46 \tLot\">46 \tLot<\/option><option value=\"47 \tLot-et-Garonne\">47 \tLot-et-Garonne<\/option><option value=\"48 \tLoz\u00e8re\">48 \tLoz\u00e8re<\/option><option value=\"49 \tMaine-et-Loire\">49 \tMaine-et-Loire<\/option><option value=\"50 \tManche\">50 \tManche<\/option><option value=\"51 \tMarne\">51 \tMarne<\/option><option value=\"52 \tHaute-Marne\">52 \tHaute-Marne<\/option><option value=\"53 \tMayenne\">53 \tMayenne<\/option><option value=\"54 \tMeurthe-et-Moselle\">54 \tMeurthe-et-Moselle<\/option><option value=\"55 \tMeuse\">55 \tMeuse<\/option><option value=\"56 \tMorbihan\">56 \tMorbihan<\/option><option value=\"57 \tMoselle\">57 \tMoselle<\/option><option value=\"58 \tNi\u00e8vre\">58 \tNi\u00e8vre<\/option><option value=\"59 \tNord\">59 \tNord<\/option><option value=\"60 \tOise\">60 \tOise<\/option><option value=\"61 \tOrne\">61 \tOrne<\/option><option value=\"62 \tPas-de-Calais\">62 \tPas-de-Calais<\/option><option value=\"63 \tPuy-de-D\u00f4me\">63 \tPuy-de-D\u00f4me<\/option><option value=\"64 \tPyr\u00e9n\u00e9es-Atlantiques\">64 \tPyr\u00e9n\u00e9es-Atlantiques<\/option><option value=\"65 \tHautes-Pyr\u00e9n\u00e9es\">65 \tHautes-Pyr\u00e9n\u00e9es<\/option><option value=\"66 \tPyr\u00e9n\u00e9es-Orientales\">66 \tPyr\u00e9n\u00e9es-Orientales<\/option><option value=\"67 \tBas-Rhin\">67 \tBas-Rhin<\/option><option value=\"68 \tHaut-Rhin\">68 \tHaut-Rhin<\/option><option value=\"69 \tRh\u00f4ne\">69 \tRh\u00f4ne<\/option><option value=\"70 \tHaute-Sa\u00f4ne\">70 \tHaute-Sa\u00f4ne<\/option><option value=\"71 \tSa\u00f4ne-et-Loire\">71 \tSa\u00f4ne-et-Loire<\/option><option value=\"72 \tSarthe\">72 \tSarthe<\/option><option value=\"73 \tSavoie\">73 \tSavoie<\/option><option value=\"74 \tHaute-Savoie\">74 \tHaute-Savoie<\/option><option value=\"75 \tParis\">75 \tParis<\/option><option value=\"76 \tSeine-Maritime\">76 \tSeine-Maritime<\/option><option value=\"77 \tSeine-et-Marne\">77 \tSeine-et-Marne<\/option><option value=\"78 \tYvelines\">78 \tYvelines<\/option><option value=\"79 \tDeux-S\u00e8vres\">79 \tDeux-S\u00e8vres<\/option><option value=\"80 \tSomme\">80 \tSomme<\/option><option value=\"81 \tTarn\">81 \tTarn<\/option><option value=\"82 \tTarn-et-Garonne\">82 \tTarn-et-Garonne<\/option><option value=\"83 \tVar\">83 \tVar<\/option><option value=\"84 \tVaucluse\">84 \tVaucluse<\/option><option value=\"85 \tVend\u00e9e\">85 \tVend\u00e9e<\/option><option value=\"86 \tVienne\">86 \tVienne<\/option><option value=\"87 \tHaute-Vienne\">87 \tHaute-Vienne<\/option><option value=\"88 \tVosges\">88 \tVosges<\/option><option value=\"89 \tYonne\">89 \tYonne<\/option><option value=\"90 \tTerritoire de Belfort\">90 \tTerritoire de Belfort<\/option><option value=\"91 \tEssonne\">91 \tEssonne<\/option><option value=\"92 \tHauts-de-Seine\">92 \tHauts-de-Seine<\/option><option value=\"93 \tSeine-St-Denis\">93 \tSeine-St-Denis<\/option><option value=\"94 \tVal-de-Marne\">94 \tVal-de-Marne<\/option><option value=\"95 \tVal D&#039;Oise\">95 \tVal D&#039;Oise<\/option><option value=\"971 \tGuadeloupe\">971 \tGuadeloupe<\/option><option value=\"972 \tMartinique\">972 \tMartinique<\/option><option value=\"973 \tGuyane\">973 \tGuyane<\/option><option value=\"974 \tLa R\u00e9union\">974 \tLa R\u00e9union<\/option><option value=\"976 \tMayotte\">976 \tMayotte<\/option><\/select><\/span> <\/label><br \/>\n<label> Votre e-mail<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label><br \/>\n<label> T\u00e9l\u00e9phone<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-252\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-252\" \/><\/span> <\/label><br \/>\n<label>S\u00e9lectionnez la race ci-dessous<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"select-87\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"select-87\"><option value=\"Ch\u00e8vre Poitevine\">Ch\u00e8vre Poitevine<\/option><option value=\"Ch\u00e8vre Pyr\u00e9n\u00e9enne\">Ch\u00e8vre Pyr\u00e9n\u00e9enne<\/option><option value=\"Ch\u00e8vre de Lorraine\">Ch\u00e8vre de Lorraine<\/option><option value=\"Ch\u00e8vre du Rove\">Ch\u00e8vre du Rove<\/option><option value=\"Ch\u00e8vre Proven\u00e7ale\">Ch\u00e8vre Proven\u00e7ale<\/option><option value=\"Ch\u00e8vre des Savoie\">Ch\u00e8vre des Savoie<\/option><option value=\"Ch\u00e8vre des foss\u00e9s\">Ch\u00e8vre des foss\u00e9s<\/option><option value=\"Ch\u00e8vre du Massif central\">Ch\u00e8vre du Massif central<\/option><option value=\"Ch\u00e8vre angora\">Ch\u00e8vre angora<\/option><\/select><\/span><br \/>\n<label> Objet de votre contact<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label><br \/>\n<label> Votre message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap kc_captcha\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" ><span class=\"cf7ic_instructions\">Veuillez prouver que vous \u00eates humain en s\u00e9lectionnant<span> l\u2019\u00e9toile<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M350 99c-54 0-98-35-166-35-25 0-47 4-68 12a56 56 0 004-24C118 24 95 1 66 0a56 56 0 00-34 102v386c0 13 11 24 24 24h16c13 0 24-11 24-24v-94c28-12 64-23 114-23 54 0 98 35 166 35 48 0 86-16 122-41 9-6 14-15 14-26V96c0-23-24-39-45-29-35 16-77 32-117 32z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/><\/b>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"86\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n            <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d77cc3\" data-id=\"5d77cc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5be20f8 elementor-widget elementor-widget-text-editor\" data-id=\"5be20f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En 1980, la sonnette d\u2019alarme est tir\u00e9e par le lyc\u00e9e agricole de Melle, il ne reste que 6 \u00e9levage r\u00e9pertori\u00e9s et 600 ch\u00e8vres. En 1986, l\u2019Association pour la D\u00e9fense et le D\u00e9veloppement de la Ch\u00e8vre Poitevine est cr\u00e9\u00e9e et retrouve rapidement 29 \u00e9leveurs adh\u00e9rents avec 1000 animaux. Depuis les effectifs n\u2019ont cess\u00e9 de progresser. En 2015, on compte environ 3600 ch\u00e8vres laiti\u00e8res r\u00e9parties dans plus de 110 \u00e9levages en France..<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1ac900 elementor-widget elementor-widget-image\" data-id=\"d1ac900\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/bandeauaddcp3.jpg?fit=180%2C180&amp;ssl=1\" class=\"attachment-large size-large wp-image-172\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/bandeauaddcp3.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/bandeauaddcp3.jpg?zoom=2&amp;resize=180%2C180&amp;ssl=1 360w, https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/bandeauaddcp3.jpg?zoom=3&amp;resize=180%2C180&amp;ssl=1 540w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0275bf elementor-widget elementor-widget-text-editor\" data-id=\"e0275bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.helloasso.com\/associations\/association-pour-la-defense-et-le-developpement-de-la-chevre-poitevine\/formulaires\/1\/widget\" target=\"_blank\" rel=\"noopener noreferrer\">\u00c9leveurs, l\u2019ADDCP a besoin de votre soutien..<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d35108e elementor-widget elementor-widget-image\" data-id=\"d35108e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/logoaddcp2012.jpg?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-image-139\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/logoaddcp2012.jpg?w=572&amp;ssl=1 572w, https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/logoaddcp2012.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.fermeduvieuxchene.fr\/wp-content\/uploads\/2022\/06\/logoaddcp2012.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7aae719 elementor-widget elementor-widget-text-editor\" data-id=\"7aae719\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Source :<\/strong> <a href=\"http:\/\/www.chevre-poitevine.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Association pour la sauvegarde et le d\u00e9veloppement de la Ch\u00e8vre Poitevine<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d91cee4 elementor-widget elementor-widget-text-editor\" data-id=\"d91cee4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Consultez et t\u00e9l\u00e9chargez la brochure de l&rsquo;ADDCP S&rsquo;installer en Ch\u00e8vre Poitevine<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e22405c elementor-widget elementor-widget-text-editor\" data-id=\"e22405c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"_df_book df-lite\" id=\"df_1159\"  _slug=\"chevrepoitevineinstallation\" data-title=\"chevrepoitevineinstallation\" wpoptions=\"true\" thumbtype=\"\" ><\/div><script class=\"df-shortcode-script\" nowprocket type=\"application\/javascript\">window.option_df_1159 = {\"outline\":[],\"autoEnableOutline\":\"false\",\"autoEnableThumbnail\":\"false\",\"overwritePDFOutline\":\"false\",\"direction\":\"1\",\"pageSize\":\"0\",\"source\":\"https:\\\/\\\/www.fermeduvieuxchene.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/addcp-pochette-installation.pdf\",\"wpOptions\":\"true\"}; if(window.DFLIP && window.DFLIP.parseBooks){window.DFLIP.parseBooks();}<\/script>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a122a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a122a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e02883\" data-id=\"9e02883\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18bdfd1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"18bdfd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le berceau de la race Poitevine se situe aux alentours des sources de la S\u00e8vre, dans le Centre-Ouest de la France en r\u00e9gion Poitou-Charentes. Type: La ch\u00e8vre poitevine est un animal de format moyen et d\u2019aspect longiligne. Robe et poil: La robe comporte des poils d\u2019un brun plus ou moins fonc\u00e9, allant parfois jusqu\u2019au noir:&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"folder":[],"class_list":["post-160","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fermeduvieuxchene.fr\/index.php\/wp-json\/wp\/v2\/pages\/160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fermeduvieuxchene.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fermeduvieuxchene.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fermeduvieuxchene.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fermeduvieuxchene.fr\/index.php\/wp-json\/wp\/v2\/comments?post=160"}],"version-history":[{"count":37,"href":"https:\/\/www.fermeduvieuxchene.fr\/index.php\/wp-json\/wp\/v2\/pages\/160\/revisions"}],"predecessor-version":[{"id":1166,"href":"https:\/\/www.fermeduvieuxchene.fr\/index.php\/wp-json\/wp\/v2\/pages\/160\/revisions\/1166"}],"wp:attachment":[{"href":"https:\/\/www.fermeduvieuxchene.fr\/index.php\/wp-json\/wp\/v2\/media?parent=160"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/www.fermeduvieuxchene.fr\/index.php\/wp-json\/wp\/v2\/folder?post=160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}